{"id":17196,"date":"2024-03-04T18:09:39","date_gmt":"2024-03-04T17:09:39","guid":{"rendered":"https:\/\/restauraciofisandeco.com\/product\/tauleta-de-nit\/"},"modified":"2024-03-04T18:58:15","modified_gmt":"2024-03-04T17:58:15","slug":"mesita-de-noche","status":"publish","type":"product","link":"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/","title":{"rendered":"Mesita de noche"},"content":{"rendered":"<h2>Descripci\u00f3n<\/h2>\n<p><span style=\"color: #888;\">Mesita de noche con caj\u00f3n y puerta. Acabado desgastado y estampado.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n Mesita de noche con caj\u00f3n y puerta. Acabado desgastado y estampado.<\/p>\n","protected":false},"featured_media":17605,"template":"","meta":[],"product_cat":[630,137],"product_tag":[],"class_list":["post-17196","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-mesitas-de-noche","product_cat-muebles-de-interior-y-exterior"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mesita de noche - Fisandeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesita de noche - Fisandeco\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n Mesita de noche con caj\u00f3n y puerta. Acabado desgastado y estampado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/\" \/>\n<meta property=\"og:site_name\" content=\"Fisandeco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/fisandeco\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-04T17:58:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/restauraciofisandeco.com\/wp-content\/uploads\/2024\/03\/IMG_20240304_164714.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2545\" \/>\n\t<meta property=\"og:image:height\" content=\"3210\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/\",\"url\":\"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/\",\"name\":\"Mesita de noche - Fisandeco\",\"isPartOf\":{\"@id\":\"https:\/\/restauraciofisandeco.com\/ca\/#website\"},\"datePublished\":\"2024-03-04T17:09:39+00:00\",\"dateModified\":\"2024-03-04T17:58:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/restauraciofisandeco.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/restauraciofisandeco.com\/es\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mesita de noche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/restauraciofisandeco.com\/ca\/#website\",\"url\":\"https:\/\/restauraciofisandeco.com\/ca\/\",\"name\":\"Fisandeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/restauraciofisandeco.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/restauraciofisandeco.com\/ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/restauraciofisandeco.com\/ca\/#organization\",\"name\":\"Fisandeco\",\"url\":\"https:\/\/restauraciofisandeco.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/restauraciofisandeco.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/restauraciofisandeco.com\/wp-content\/uploads\/2023\/09\/logo.jpg\",\"contentUrl\":\"https:\/\/restauraciofisandeco.com\/wp-content\/uploads\/2023\/09\/logo.jpg\",\"width\":316,\"height\":316,\"caption\":\"Fisandeco\"},\"image\":{\"@id\":\"https:\/\/restauraciofisandeco.com\/ca\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es-es.facebook.com\/fisandeco\/\",\"https:\/\/www.instagram.com\/fisandeco\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesita de noche - Fisandeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/","og_locale":"es_ES","og_type":"article","og_title":"Mesita de noche - Fisandeco","og_description":"Descripci\u00f3n Mesita de noche con caj\u00f3n y puerta. Acabado desgastado y estampado.","og_url":"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/","og_site_name":"Fisandeco","article_publisher":"https:\/\/es-es.facebook.com\/fisandeco\/","article_modified_time":"2024-03-04T17:58:15+00:00","og_image":[{"width":2545,"height":3210,"url":"https:\/\/restauraciofisandeco.com\/wp-content\/uploads\/2024\/03\/IMG_20240304_164714.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/","url":"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/","name":"Mesita de noche - Fisandeco","isPartOf":{"@id":"https:\/\/restauraciofisandeco.com\/ca\/#website"},"datePublished":"2024-03-04T17:09:39+00:00","dateModified":"2024-03-04T17:58:15+00:00","breadcrumb":{"@id":"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/restauraciofisandeco.com\/es\/producto\/mesita-de-noche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/restauraciofisandeco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/restauraciofisandeco.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Mesita de noche"}]},{"@type":"WebSite","@id":"https:\/\/restauraciofisandeco.com\/ca\/#website","url":"https:\/\/restauraciofisandeco.com\/ca\/","name":"Fisandeco","description":"","publisher":{"@id":"https:\/\/restauraciofisandeco.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/restauraciofisandeco.com\/ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/restauraciofisandeco.com\/ca\/#organization","name":"Fisandeco","url":"https:\/\/restauraciofisandeco.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/restauraciofisandeco.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/restauraciofisandeco.com\/wp-content\/uploads\/2023\/09\/logo.jpg","contentUrl":"https:\/\/restauraciofisandeco.com\/wp-content\/uploads\/2023\/09\/logo.jpg","width":316,"height":316,"caption":"Fisandeco"},"image":{"@id":"https:\/\/restauraciofisandeco.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/fisandeco\/","https:\/\/www.instagram.com\/fisandeco\/"]}]}},"_links":{"self":[{"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/product\/17196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/product\/17196\/revisions"}],"predecessor-version":[{"id":17198,"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/product\/17196\/revisions\/17198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/media\/17605"}],"wp:attachment":[{"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/media?parent=17196"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/product_cat?post=17196"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/restauraciofisandeco.com\/es\/wp-json\/wp\/v2\/product_tag?post=17196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}